{"id":6033,"date":"2025-09-29T11:53:46","date_gmt":"2025-09-29T17:53:46","guid":{"rendered":"https:\/\/adcaraudio.com\/store\/?post_type=product&#038;p=6033"},"modified":"2026-07-14T13:32:25","modified_gmt":"2026-07-14T19:32:25","slug":"sd600-1x","status":"publish","type":"product","link":"https:\/\/adcaraudio.com\/store\/product\/sd600-1x\/","title":{"rendered":"SD600.1x"},"content":{"rendered":"<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owner_Manual_SD600.1x-500.4x-800.4x-1400.6x.pdf\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-7447\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owners-Manual-Button-1-1024x251.png\" alt=\"\" width=\"652\" height=\"160\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owners-Manual-Button-1-1024x251.png 1024w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owners-Manual-Button-1-300x74.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owners-Manual-Button-1-768x188.png 768w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owners-Manual-Button-1-1536x377.png 1536w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owners-Manual-Button-1-600x147.png 600w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Owners-Manual-Button-1.png 1615w\" sizes=\"(max-width: 652px) 100vw, 652px\" \/><\/a><\/p>\n<p>The SDx amplifiers have double the thermal capacity as the original SD amplifiers.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-6044\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-1024x1024.jpg\" alt=\"\" width=\"533\" height=\"533\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-1024x1024.jpg 1024w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-300x300.jpg 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-scaled-100x100.jpg 100w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-scaled-600x600.jpg 600w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-150x150.jpg 150w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-768x768.jpg 768w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-1536x1536.jpg 1536w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-2048x2048.jpg 2048w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-60x60.jpg 60w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/20250929_124157-90x90.jpg 90w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/p>\n<p>The top plate has also been increased from 1.3mm to 5mm thick. An additional top plate can be purchased in <strong><span style=\"color: #ff0000;\">RED<\/span><\/strong>.<\/p>\n<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td>\u00a0<strong>Continuous Power<\/strong><\/td>\n<td>250W x 1 @ 4 ohms<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>At 14.4V Supply Voltage<\/strong><\/td>\n<td>400W x 1 @ 2 ohms<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>600W x 1 @ 1 ohm<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Frequency Response<\/strong><\/td>\n<td>10Hz &#8211; 500Hz<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Input Sensitivity<\/strong><\/td>\n<td>200mV &#8211; 6V (low) 500mV &#8211; 10V (high level into RCA connectors)<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Fuse Ratings<\/strong><\/td>\n<td>25A @ 4 ohms \/ 35A @ 2 ohms \/ 60A @ 1 ohm<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Filter Modes<\/strong><\/td>\n<td>Subsonic and Low Pass<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>High Pass Filter @ 24dB\/Oct<\/strong><\/td>\n<td style=\"text-align: left;\">10Hz \u2013 50Hz<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-478\" src=\"http:\/\/audiodynamicsdesigns.com\/wp-content\/uploads\/bullet_clear.png\" alt=\"\" width=\"15\" height=\"15\" \/><strong>Linkwitz-Riley<\/strong><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Low Pass Filter @ 24dB\/Oct<\/strong><\/td>\n<td>50Hz \u2013 500Hz<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<img decoding=\"async\" class=\"alignnone size-full wp-image-478\" src=\"http:\/\/audiodynamicsdesigns.com\/wp-content\/uploads\/bullet_clear.png\" alt=\"\" width=\"15\" height=\"15\" \/><strong>Linkwitz-Riley<\/strong><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Detented Filter Potentiometers<\/strong><\/td>\n<td>41 Click-in-Place Frequencies<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Remote Level Control<\/strong><\/td>\n<td>Included with clip indicator<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Pass-Through Output<\/strong><\/td>\n<td>Yes<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Height<\/strong><\/td>\n<td>2.06 in \/ 52.2 mm<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Depth<\/strong><\/td>\n<td>4.9 in \/ 125 mm (includes terminals)<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Width<\/strong><\/td>\n<td>7.0 in \/ 178 mm (includes mounting feet)<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Net Weight<\/strong><\/td>\n<td>\u00a0lb \/\u00a0 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li>600W Mono Block Class D<\/li>\n<li>Optional <strong><span style=\"color: #ff0000;\">RED <\/span><\/strong><span style=\"color: #000000;\">Top Plate<\/span><\/li>\n<li>Xtreme Thermal Capacity Heatsink<\/li>\n<li>Controls Under Reversible Cover<\/li>\n<li>Click-in-Place Crossover Controls<\/li>\n<li>Subsonic and Low Pass Filter<\/li>\n<li>Phase Control 0-180 Degrees<\/li>\n<li>Wired Level Control with Clipping Indicator<\/li>\n<li>Low\/High Level RCA Inputs<\/li>\n<li>Auto Turn On (DC\/Signal)<\/li>\n<li>Clipping Indicator next to Sensitivity Control<\/li>\n<li>4 AWG Power Terminals<\/li>\n<li>Engineered in U.S.A. and China<\/li>\n<\/ul>\n","protected":false},"featured_media":6034,"template":"","meta":[],"product_brand":[],"product_cat":[55,17],"product_tag":[],"class_list":["post-6033","product","type-product","status-publish","has-post-thumbnail","product_cat-1-channel","product_cat-amplifiers","first","instock","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product\/6033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media\/6034"}],"wp:attachment":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media?parent=6033"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_brand?post=6033"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_cat?post=6033"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_tag?post=6033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}