{"id":686,"date":"2019-07-17T09:44:42","date_gmt":"2019-07-17T15:44:42","guid":{"rendered":"https:\/\/adcaraudio.com\/store\/?post_type=product&#038;p=686"},"modified":"2025-03-04T17:25:22","modified_gmt":"2025-03-04T23:25:22","slug":"ad2212d4","status":"publish","type":"product","link":"https:\/\/adcaraudio.com\/store\/product\/ad2212d4\/","title":{"rendered":"AD2212 D4"},"content":{"rendered":"<p>The 2200 series 12&#8243; employs a finely-tuned balance of damping and motor force to achieve high efficiency, offering exceptional versatility and performance in a variety of real-world functions:<\/p>\n<p>Paired with a traditional (4th order) bass-reflex enclosure, the subwoofer\u2019s output can be focused along a narrow bandwidth for use in sheer loudness \/ SPL applications. In a 6th order bass-reflex, the output can be spread along a wider frequency range, shifting emphasis onto sound quality with articulate delivery and highly controlled excursion.<\/p>\n<pre><strong>Fs<\/strong>\t34.32 Hz\r\n<strong>Qms<\/strong>\t6.06\r\n<strong>Vas<\/strong>\t33.68 l\r\n<strong>Cms<\/strong>\t0.09 mm\/N\r\n<strong>Mms<\/strong>\t234.00 g\r\n<strong>Rms<\/strong>\t8.40 kg\/s\r\n<strong>Dia<\/strong>\t269.56 mm\r\n<strong>Sd<\/strong>\t510.70 cm\u00b2\r\n\t\r\n<strong>Qes<\/strong>\t0.67\r\n<strong>Re<\/strong>\t7.41 \u03a9\r\n<strong>Le<\/strong>\t2.66 mH\r\n<strong>Z<\/strong>\t8.00 \u03a9\r\n<strong>Bl<\/strong>\t23.55 Tm\r\n<strong>Bl\u00b2\/Re<\/strong>\t74.85 N\u00b2\/W\r\n\r\n<strong>Qts<\/strong>\t0.60\r\n<strong>no<\/strong>\t0.19 %\r\n<strong>SPL<\/strong>\t85.04 dB\r\n<strong>EBP<\/strong>\t50.91\r\n\r\n<strong>Nominal Diameter<\/strong>\t\t12 in\r\n<strong>Overall Diameter<\/strong>\t\t12.45 in \/ 316 mm\r\n<strong>Mounting Hole Diameter<\/strong>\t\t11 in \/ 279 mm\r\n<strong>Bolt Hole Circle Diameter<\/strong>\r\n<strong>Motor Outer Diameter            <\/strong>6.30 in \/ 160 mm\r\n<strong>Mounting Depth<\/strong>\t\t\t6.30 in \/ 160 mm\r\n<strong>Required Pole Vent Clearance<\/strong>\r\n<strong>Driver Displacement<\/strong>\t\t0.136 cu ft \/ 3.87 l\r\n\r\n<strong>Minimum Sealed Volume<\/strong>\t\tN\/A\r\n<strong>Minimum Vented Volume<\/strong>\t\t1.32 cu ft \/ 38 l net*\r\n\r\n* Tune for desired response<\/pre>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-719\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented.png\" alt=\"\" width=\"800\" height=\"974\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented.png 800w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented-600x731.png 600w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented-246x300.png 246w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented-768x935.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1784\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented_dual-1024x996.png\" alt=\"\" width=\"900\" height=\"875\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented_dual-1024x996.png 1024w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented_dual-600x584.png 600w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented_dual-300x292.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented_dual-768x747.png 768w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/recommended_enc_2212_vented_dual.png 1062w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>The above designs have been engineered for a &#8220;two tier&#8221; balance of compatibility: First, between the cabin acoustics of a sedan, hatchback and an SUV, and second, between the two available voice coil configurations, for a total of six balance points. This ensures a linear response and optimal power handling for listening purposes under most circumstances. Please visit our <a href=\"https:\/\/adcaraudio.com\/store\/enclosure-design-service\/\">Enclosure Design Service<\/a> page for custom designs.<\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-3.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2652\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-sedan-4door-single-sub.png\" alt=\"\" width=\"300\" height=\"255\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-5.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2666\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-sedan-4door-dual-subs.png\" alt=\"\" width=\"300\" height=\"255\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-9.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2811\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-suv-4door-dual-subs.png\" alt=\"\" width=\"300\" height=\"255\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-32.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3319\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-truck-dual-subs.png\" alt=\"\" width=\"300\" height=\"255\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-118.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4046\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-65.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-65.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-65-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-65-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-125.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4067\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-70.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-70.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-70-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-70-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-139.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4121\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-82.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-82.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-82-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-82-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-197.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4961\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-136.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-136.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-136-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-136-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-198.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4969\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-137.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-137.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-137-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-137-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-219.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5068\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-156.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-156.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-156-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-156-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Design-226.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5108\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-163.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-163.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-163-71x60.png 71w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Web-Enclosure-Design-Button-163-106x90.png 106w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<h3><\/h3>\n<ul>\n<li>200W \u2013 600W optimal power range<\/li>\n<li>2.5&#8243; voice coil diameter<\/li>\n<li>Designed for use in vented enclosures.<\/li>\n<li>Engineered in the USA.<\/li>\n<\/ul>\n","protected":false},"featured_media":820,"template":"","meta":{"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[62],"product_tag":[],"class_list":{"0":"post-686","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-subwoofer-archives","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media\/820"}],"wp:attachment":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_brand?post=686"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_cat?post=686"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_tag?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}