{"id":7066,"date":"2026-04-21T09:40:54","date_gmt":"2026-04-21T15:40:54","guid":{"rendered":"https:\/\/adcaraudio.com\/store\/?post_type=product&#038;p=7066"},"modified":"2026-05-09T13:44:48","modified_gmt":"2026-05-09T19:44:48","slug":"dsp1216","status":"publish","type":"product","link":"https:\/\/adcaraudio.com\/store\/product\/dsp1216\/","title":{"rendered":"DSP1216"},"content":{"rendered":"<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_52443\"  width=\"900\" height=\"506\"  data-origwidth=\"900\" data-origheight=\"506\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/PLLkfWxhM6s?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7068 size-large\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Software-Hompage--1024x480.png\" alt=\"\" width=\"900\" height=\"422\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Software-Hompage--1024x480.png 1024w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Software-Hompage--300x141.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Software-Hompage--768x360.png 768w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Software-Hompage--1536x720.png 1536w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Software-Hompage--600x281.png 600w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Software-Hompage-.png 1920w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><a href=\"https:\/\/adcaraudio.com\/store\/documents\/software\/DSP1216_v1.29_6.8.16_2026_0123.exe\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1403 size-full\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_For_Windows.png\" alt=\"\" width=\"324\" height=\"84\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_For_Windows.png 324w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_For_Windows-300x78.png 300w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/a> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1404 size-full\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_For_Android.png\" alt=\"\" width=\"324\" height=\"84\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_For_Android.png 324w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_For_Android-300x78.png 300w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/p>\n<h3><span style=\"color: #ff0000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1929\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_From_Apple.png\" alt=\"\" width=\"324\" height=\"84\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_From_Apple.png 324w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/Download_From_Apple-300x78.png 300w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/strong><\/span><\/h3>\n<h2><span style=\"color: #ff0000;\"><strong>NOTE: Apps will be available by June 1st<\/strong><\/span><\/h2>\n<h3><span style=\"color: #ff0000;\"><strong>Advanced Setup password is 88888888<\/strong><\/span><\/h3>\n<table width=\"452\">\n<tbody>\n<tr>\n<td width=\"296\">Inputs<\/td>\n<td width=\"156\">8 Low Level RCA<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>12 High Level<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Built-In aptX HD\/LDAC Bluetooth Audio Streaming<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Toslink Optical Digital Input<\/td>\n<\/tr>\n<tr>\n<td>Input Sensitivity<\/td>\n<td>RCA &#8211; 400mV &#8211; 9 V<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>High Level 4V-20V<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Outputs<\/td>\n<td>16 RCA<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Output voltage<\/td>\n<td>Up to 3 Volts with all inputs<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Frequency Response<\/td>\n<td>20Hz &#8211; 20kHz<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>DSP resolution<\/td>\n<td>32 Bit<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Sampling Rate<\/td>\n<td>192kHz<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Signal Converters<\/td>\n<td>A\/D: Asahi Kasei Microdevices + Cirrus Logic<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>D\/A: Cirrus Logic<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Signal-to-Noise Ratio Analog Input<\/td>\n<td>\u00a0100dB (A-weighted)<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Signal-to-Noise Ratio High Level Input<\/td>\n<td>\u00a0100dB (A-weighted)<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Total Harmonic Distortion (THD+N) Analog Input<\/td>\n<td>&lt; % 0.01<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Total Harmonic Distortion (THD+N) High Level Input<\/td>\n<td>&lt; % 0.01<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Operating Voltage<\/td>\n<td>9 &#8211; 16 Volts<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Remote Output Current<\/td>\n<td>&gt;500mA<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Dimensions (H x W x D)<\/td>\n<td>1.8&#8243; x 9.11&#8243; x 6.3&#8243;<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>46 x 232 x 160 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<h3><\/h3>\n<ul>\n<li>12 in &#8211; 16 out DSP<\/li>\n<li>Easy Use Software<\/li>\n<li>Built-in aptX HD\/LDAC Bluetooth Audio Streaming<\/li>\n<li>Direct Digital Input for Android<\/li>\n<li>Toslink Optical Digital Input<\/li>\n<li>Wired Controller (Optional)<\/li>\n<li>4-Position Logo Top Plate<\/li>\n<li>PC Control<\/li>\n<li>APP Control<\/li>\n<li>3 Volt Outputs<\/li>\n<li>Level Control with Clip Indicator<\/li>\n<li>Parametric EQ per Channel<\/li>\n<li>Time Alignment<\/li>\n<li>6\/12\/18\/24\/30\/36\/42\/48 dB\/Oct Crossovers<\/li>\n<li>10 Memory Presets<\/li>\n<li>Auto Turn On for High Level Inputs<\/li>\n<\/ul>\n","protected":false},"featured_media":7067,"template":"","meta":{"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[42,88],"product_tag":[],"class_list":{"0":"post-7066","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dsp","7":"product_cat-manual-tune","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product\/7066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media\/7067"}],"wp:attachment":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media?parent=7066"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_brand?post=7066"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_cat?post=7066"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_tag?post=7066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}