{"id":910,"date":"2019-08-29T14:27:00","date_gmt":"2019-08-29T20:27:00","guid":{"rendered":"https:\/\/adcaraudio.com\/store\/?post_type=product&#038;p=910"},"modified":"2025-01-24T16:31:05","modified_gmt":"2025-01-24T22:31:05","slug":"adk1800-6","status":"publish","type":"product","link":"https:\/\/adcaraudio.com\/store\/product\/adk1800-6\/","title":{"rendered":"ADK1800.6"},"content":{"rendered":"<table border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><strong>Continuous Power<\/strong><\/td>\n<td>170W x 4 + 350W x 2 @ 4 ohms<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a014.4V Supply Voltage<\/strong><\/td>\n<td>240W x 4 + 500W x 2 @ 2 ohms<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Bridged<\/strong><\/td>\n<td>480W x 2 + 1000W x 1 @ 4 ohms<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Frequency Response<\/strong><\/td>\n<td>10Hz \u2013 35KHz<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Input Sensitivity<\/strong><\/td>\n<td>0.2V to 6V<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Recommended Fuse Ratings<\/strong><\/td>\n<td>125A @ 4 ohms \/ 175A @ 2 ohms<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Filter Modes<\/strong><\/td>\n<td>High Pass \u2013 Low Pass \u2013 Band Pass<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0High Pass Filter<\/strong><\/td>\n<td>Ch 1+2: 50Hz \u2013 5KHz<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0At 12dB\/Oct Slope<\/strong><\/td>\n<td>Ch 3+4: 50Hz \u2013 5KHz<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Linkwitz-Riley<\/strong><\/td>\n<td>Ch 5+6: 10Hz \u2013 1KHz<\/td>\n<\/tr>\n<tr>\n<td>\u00a0<strong>Low Pass Filter<\/strong><\/td>\n<td>Ch 1+2: N\/A<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0At 12dB\/Oct Slope<\/strong><\/td>\n<td>Ch 3+4: 50Hz \u2013 5KHz<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Linkwitz-Riley<\/strong><\/td>\n<td>Ch 5+6: 50Hz \u2013 5KHz<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Detented Filter Potentiometers<\/strong><\/td>\n<td>41 Click-in-Place Frequencies<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Remote Level Control w\/ Clip Indicator<\/strong><\/td>\n<td>Included<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Height<\/strong><\/td>\n<td>2.64 in \/ 67 mm<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Width<\/strong><\/td>\n<td>7.54 in \/ 191.4 mm<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Length<\/strong><\/td>\n<td>17.73 in \/ 450.3 mm<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0Net Weight<\/strong><\/td>\n<td>13 lb \/ 5.9 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"color: #ff0000;\"><strong>Amp Dyno Numbers<\/strong><\/span><\/p>\n<div id='gallery-1' class='gallery galleryid-910 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adcaraudio.com\/store\/?attachment_id=1016'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1016\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-150x150.png 150w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-300x300.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1016'>\n\t\t\t\tChannels 1-4 @ 4 ohm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adcaraudio.com\/store\/?attachment_id=1014'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-2ohm-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1014\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-2ohm-150x150.png 150w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-2ohm-300x300.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-2ohm-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1014'>\n\t\t\t\tChannels 1-4 @ 2 ohm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adcaraudio.com\/store\/?attachment_id=1019'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1019\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-150x150.png 150w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-300x300.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1019'>\n\t\t\t\tChannels 5-6 @ 4 ohm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adcaraudio.com\/store\/?attachment_id=1017'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-2ohm-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1017\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-2ohm-150x150.png 150w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-2ohm-300x300.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-2ohm-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1017'>\n\t\t\t\tChannels 5-6 @ 2 ohm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adcaraudio.com\/store\/?attachment_id=1015'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-Bridged-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1015\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-Bridged-150x150.png 150w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-Bridged-300x300.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH1-4-4ohm-Bridged-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1015'>\n\t\t\t\tCH 1-4 Bridged @ 4 ohm\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adcaraudio.com\/store\/?attachment_id=1018'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-Bridged-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1018\" srcset=\"https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-Bridged-150x150.png 150w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-Bridged-300x300.png 300w, https:\/\/adcaraudio.com\/store\/wp-content\/uploads\/K1800.6-CH5-6-4ohm-Bridged-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1018'>\n\t\t\t\tCH 5-6 Bridged @ 4 ohm\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li>Full Range Class D 6 Channel<\/li>\n<li>Discrete Hi-Fidelity Design<\/li>\n<li>Click-in-Place Crossover Controls<\/li>\n<li>Band Pass Capable<\/li>\n<li>Fan Cooled with 60 mm Fan<\/li>\n<li>Tiffany Style RCA Connectors<\/li>\n<li>Engineered in U.S.A and Korea<\/li>\n<\/ul>\n","protected":false},"featured_media":1414,"template":"","meta":[],"product_brand":[],"product_cat":[60],"product_tag":[],"class_list":["post-910","product","type-product","status-publish","has-post-thumbnail","product_cat-amplifier-archives","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product\/910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media\/1414"}],"wp:attachment":[{"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/media?parent=910"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_brand?post=910"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_cat?post=910"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adcaraudio.com\/store\/wp-json\/wp\/v2\/product_tag?post=910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}